






{"id":59510,"date":"2025-06-09T11:01:16","date_gmt":"2025-06-09T15:01:16","guid":{"rendered":"https:\/\/cupe.on.ca\/the-society-of-united\/"},"modified":"2025-06-16T09:39:23","modified_gmt":"2025-06-16T13:39:23","slug":"the-society-of-united","status":"publish","type":"post","link":"https:\/\/cupe.on.ca\/fr\/the-society-of-united\/","title":{"rendered":"La Society of United Professionals se joindra \u00e0 la ligne de piquetage de la CSPAAT pour souligner le 20e anniversaire de sa gr\u00e8ve historique"},"content":{"rendered":"<div id=\"main-content\" class=\"u-2-3\" role=\"main\">\n<div class=\"ds-1col node node-basic-page cupe-ia-news view-mode-full clearfix\">\n<div class=\"field field-name-body field-type-text-with-summary\">\n<p>Le personnel de premi\u00e8re ligne de la CSPAAT, en Ontario, continue de lutter pour une paie \u00e9quitable, la s\u00e9curit\u00e9 au travail et la s\u00e9curit\u00e9 d\u2019emploi sous le signe de la solidarit\u00e9\u00a0intersyndicale.<\/p>\n<p>Les membres de la Society of United Professionals, soit la section locale 160 de l\u2019IFPTE, se joindra \u00e0 la ligne de piquetage en cours au 200\u00a0Front Street West, le lundi 9\u00a0juin\u00a02025, pour montrer son soutien aux 3\u00a0600\u00a0travailleuses et travailleurs en gr\u00e8ve de la CSPAAT qui sont repr\u00e9sent\u00e9s par l\u2019Ontario Compensation Employees Union (SCFP 1750-OCEU). Ce signe de solidarit\u00e9 arrive au moment o\u00f9 l\u2019OCEU entame une troisi\u00e8me semaine de gr\u00e8ve pour revendiquer des salaires \u00e9quitables, des milieux de travail s\u00e9curitaires et la fin de la sous-traitance d\u2019emplois ontariens n\u00e9vralgiques \u00e0 des entreprises\u00a0am\u00e9ricaines.<\/p>\n<p>Environ 170\u00a0membres de la Society of United Professionals s\u2019ajouteront \u00e0 la ligne de piquetage des membres du SCFP\u00a01750-OCEU.\u00a0 Cette action co\u00efncide avec le 20<sup>e\u00a0<\/sup>anniversaire de la gr\u00e8ve de 105\u00a0jours tenue par les travailleuses et travailleurs d\u2019Hydro One membres de la Society of United Professionals, un moment charni\u00e8re de l\u2019histoire syndicale en\u00a0Ontario.<\/p>\n<p>Les personnes suivantes prendront la parole lors d\u2019un rassemblement pr\u00e9vu \u00e0\u00a010\u00a0h\u00a0:<\/p>\n<ul>\n<li>Matt Biggs, pr\u00e9sident de\u00a0l\u2019IFPTE<\/li>\n<li>Rebecca Caron, pr\u00e9sidente de la Society of United Professionals (la section locale 160 de l\u2019IFPTE)<\/li>\n<li>Vicky Power, vice-pr\u00e9sidente \u00e0 la section locale d\u2019Hydro\u00a0One<\/li>\n<\/ul>\n<p>\u00ab\u00a0Les travailleuses et les travailleurs du secteur public en Ontario s\u2019unissent pour demander le respect, une paie \u00e9quitable et des conditions de travail s\u00fbres. On conna\u00eet d\u2019exp\u00e9rience les d\u00e9fis qui se pr\u00e9sentent \u00e0 nous quand on d\u00e9fend ce qui est juste, et c\u2019est avec fiert\u00e9 qu\u2019on pr\u00eate main-forte aux membres du SCFP\u00a01750-OCEU dans cette lutte qui concerne toute la population ontarienne\u00a0\u00bb, souligne Matt Biggs, le pr\u00e9sident de\u00a0l\u2019IFPTE.<\/p>\n<p>Depuis le d\u00e9but du conflit, le personnel de la CSPAAT fait face \u00e0 un manque chronique de main-d\u2019\u0153uvre, \u00e0 une stagnation des salaires, ainsi qu\u2019\u00e0 la pression croissante de voir des services primordiaux \u00eatre sous-trait\u00e9s. La gr\u00e8ve en cours met en \u00e9vidence l\u2019urgent besoin d\u2019investissements de la part du gouvernement et de la direction \u00e0 l\u2019endroit des emplois et des services publics dans la province, plut\u00f4t que de sous-traiter le travail au sud de la\u00a0fronti\u00e8re.<\/p>\n<p>\u00ab\u00a0C\u2019est avec une profonde gratitude que l\u2019on voit la Society of United Professionals et l\u2019IFPTE se joindre \u00e0 nous pour piqueter. Leur geste de solidarit\u00e9 envoie un message fort \u00e0 l\u2019employeur et \u00e0 l\u2019ensemble du mouvement syndical\u00a0: quand les travailleuses et travailleurs s\u2019unissent, on accro\u00eet notre force et la port\u00e9e de notre message, de sorte qu\u2019on ne peut plus \u00eatre ignor\u00e9(e)s\u00a0\u00bb, exprime Harry Goslin, pr\u00e9sident du\u00a0SCFP\u00a01750-OCEU.<\/p>\n<p>Une petite d\u00e9l\u00e9gation de la Society of United Professionals tentera \u00e9galement de remettre une lettre de solidarit\u00e9 au pr\u00e9sident de la CSPAAT, Jeffery Lang, de la part de 90\u00a0000\u00a0membres de l\u2019IFPTE partout en Am\u00e9rique du Nord, pour souligner les pr\u00e9occupations croissantes quant \u00e0 l\u2019inaction dangereuse du gouvernement Ford en mati\u00e8re de surcharge de travail et de sous-traitance d\u2019emplois\u00a0ontariens.<\/p>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Le personnel de premi\u00e8re ligne de la CSPAAT, en Ontario, continue de lutter pour une paie \u00e9quitable, la s\u00e9curit\u00e9 au travail et la s\u00e9curit\u00e9 d\u2019emploi sous le signe de la solidarit\u00e9\u00a0intersyndicale. Les membres de la Society of United Professionals, soit la section locale 160 de l\u2019IFPTE, se joindra \u00e0 la ligne de piquetage en cours&hellip;<\/p>\n","protected":false},"author":21,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[247],"tags":[],"class_list":["post-59510","post","type-post","status-publish","format-standard","hentry","category-la-solidarite","category-247","description-off"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La Society of United Professionals se joindra \u00e0 la ligne de piquetage de la CSPAAT pour souligner le 20e anniversaire de sa gr\u00e8ve historique - SCFP-Ontario<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cupe.on.ca\/fr\/the-society-of-united\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La Society of United Professionals se joindra \u00e0 la ligne de piquetage de la CSPAAT pour souligner le 20e anniversaire de sa gr\u00e8ve historique - SCFP-Ontario\" \/>\n<meta property=\"og:description\" content=\"Le personnel de premi\u00e8re ligne de la CSPAAT, en Ontario, continue de lutter pour une paie \u00e9quitable, la s\u00e9curit\u00e9 au travail et la s\u00e9curit\u00e9 d\u2019emploi sous le signe de la solidarit\u00e9\u00a0intersyndicale. Les membres de la Society of United Professionals, soit la section locale 160 de l\u2019IFPTE, se joindra \u00e0 la ligne de piquetage en cours&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cupe.on.ca\/fr\/the-society-of-united\/\" \/>\n<meta property=\"og:site_name\" content=\"SCFP-Ontario\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/CUPEOntario\" \/>\n<meta property=\"article:published_time\" content=\"2025-06-09T15:01:16+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-06-16T13:39:23+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cupe.on.ca\/wp-content\/uploads\/2020\/09\/cupetwitter2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Alisha Sharma\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@CUPEOntario\" \/>\n<meta name=\"twitter:site\" content=\"@CUPEOntario\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/cupe.on.ca\\\/fr\\\/the-society-of-united\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cupe.on.ca\\\/fr\\\/the-society-of-united\\\/\"},\"author\":{\"name\":\"Alisha Sharma\",\"@id\":\"https:\\\/\\\/cupe.on.ca\\\/fr\\\/#\\\/schema\\\/person\\\/0a67c9ec31b14c86d26e95dc2a13e3dc\"},\"headline\":\"La Society of United Professionals se joindra \u00e0 la ligne de piquetage de la CSPAAT pour souligner le 20e anniversaire de sa gr\u00e8ve historique\",\"datePublished\":\"2025-06-09T15:01:16+00:00\",\"dateModified\":\"2025-06-16T13:39:23+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/cupe.on.ca\\\/fr\\\/the-society-of-united\\\/\"},\"wordCount\":573,\"articleSection\":[\"La solidarit\u00e9\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/cupe.on.ca\\\/fr\\\/the-society-of-united\\\/\",\"url\":\"https:\\\/\\\/cupe.on.ca\\\/fr\\\/the-society-of-united\\\/\",\"name\":\"La Society of United Professionals se joindra \u00e0 la ligne de piquetage de la CSPAAT pour souligner le 20e anniversaire de sa gr\u00e8ve historique - SCFP-Ontario\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cupe.on.ca\\\/fr\\\/#website\"},\"datePublished\":\"2025-06-09T15:01:16+00:00\",\"dateModified\":\"2025-06-16T13:39:23+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/cupe.on.ca\\\/fr\\\/#\\\/schema\\\/person\\\/0a67c9ec31b14c86d26e95dc2a13e3dc\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/cupe.on.ca\\\/fr\\\/the-society-of-united\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/cupe.on.ca\\\/fr\\\/the-society-of-united\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/cupe.on.ca\\\/fr\\\/the-society-of-united\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/cupe.on.ca\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La Society of United Professionals se joindra \u00e0 la ligne de piquetage de la CSPAAT pour souligner le 20e anniversaire de sa gr\u00e8ve historique\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cupe.on.ca\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/cupe.on.ca\\\/fr\\\/\",\"name\":\"SCFP-Ontario\",\"description\":\"B\u00e2tir Un Ontario Meilleur\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/cupe.on.ca\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/cupe.on.ca\\\/fr\\\/#\\\/schema\\\/person\\\/0a67c9ec31b14c86d26e95dc2a13e3dc\",\"name\":\"Alisha Sharma\",\"url\":\"https:\\\/\\\/cupe.on.ca\\\/fr\\\/author\\\/asharmacupe-on-ca\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La Society of United Professionals se joindra \u00e0 la ligne de piquetage de la CSPAAT pour souligner le 20e anniversaire de sa gr\u00e8ve historique - SCFP-Ontario","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cupe.on.ca\/fr\/the-society-of-united\/","og_locale":"fr_FR","og_type":"article","og_title":"La Society of United Professionals se joindra \u00e0 la ligne de piquetage de la CSPAAT pour souligner le 20e anniversaire de sa gr\u00e8ve historique - SCFP-Ontario","og_description":"Le personnel de premi\u00e8re ligne de la CSPAAT, en Ontario, continue de lutter pour une paie \u00e9quitable, la s\u00e9curit\u00e9 au travail et la s\u00e9curit\u00e9 d\u2019emploi sous le signe de la solidarit\u00e9\u00a0intersyndicale. Les membres de la Society of United Professionals, soit la section locale 160 de l\u2019IFPTE, se joindra \u00e0 la ligne de piquetage en cours&hellip;","og_url":"https:\/\/cupe.on.ca\/fr\/the-society-of-united\/","og_site_name":"SCFP-Ontario","article_publisher":"https:\/\/facebook.com\/CUPEOntario","article_published_time":"2025-06-09T15:01:16+00:00","article_modified_time":"2025-06-16T13:39:23+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/cupe.on.ca\/wp-content\/uploads\/2020\/09\/cupetwitter2.jpg","type":"image\/jpeg"}],"author":"Alisha Sharma","twitter_card":"summary_large_image","twitter_creator":"@CUPEOntario","twitter_site":"@CUPEOntario","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/cupe.on.ca\/fr\/the-society-of-united\/#article","isPartOf":{"@id":"https:\/\/cupe.on.ca\/fr\/the-society-of-united\/"},"author":{"name":"Alisha Sharma","@id":"https:\/\/cupe.on.ca\/fr\/#\/schema\/person\/0a67c9ec31b14c86d26e95dc2a13e3dc"},"headline":"La Society of United Professionals se joindra \u00e0 la ligne de piquetage de la CSPAAT pour souligner le 20e anniversaire de sa gr\u00e8ve historique","datePublished":"2025-06-09T15:01:16+00:00","dateModified":"2025-06-16T13:39:23+00:00","mainEntityOfPage":{"@id":"https:\/\/cupe.on.ca\/fr\/the-society-of-united\/"},"wordCount":573,"articleSection":["La solidarit\u00e9"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/cupe.on.ca\/fr\/the-society-of-united\/","url":"https:\/\/cupe.on.ca\/fr\/the-society-of-united\/","name":"La Society of United Professionals se joindra \u00e0 la ligne de piquetage de la CSPAAT pour souligner le 20e anniversaire de sa gr\u00e8ve historique - SCFP-Ontario","isPartOf":{"@id":"https:\/\/cupe.on.ca\/fr\/#website"},"datePublished":"2025-06-09T15:01:16+00:00","dateModified":"2025-06-16T13:39:23+00:00","author":{"@id":"https:\/\/cupe.on.ca\/fr\/#\/schema\/person\/0a67c9ec31b14c86d26e95dc2a13e3dc"},"breadcrumb":{"@id":"https:\/\/cupe.on.ca\/fr\/the-society-of-united\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cupe.on.ca\/fr\/the-society-of-united\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/cupe.on.ca\/fr\/the-society-of-united\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/cupe.on.ca\/fr\/"},{"@type":"ListItem","position":2,"name":"La Society of United Professionals se joindra \u00e0 la ligne de piquetage de la CSPAAT pour souligner le 20e anniversaire de sa gr\u00e8ve historique"}]},{"@type":"WebSite","@id":"https:\/\/cupe.on.ca\/fr\/#website","url":"https:\/\/cupe.on.ca\/fr\/","name":"SCFP-Ontario","description":"B\u00e2tir Un Ontario Meilleur","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cupe.on.ca\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/cupe.on.ca\/fr\/#\/schema\/person\/0a67c9ec31b14c86d26e95dc2a13e3dc","name":"Alisha Sharma","url":"https:\/\/cupe.on.ca\/fr\/author\/asharmacupe-on-ca\/"}]}},"_links":{"self":[{"href":"https:\/\/cupe.on.ca\/fr\/wp-json\/wp\/v2\/posts\/59510","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cupe.on.ca\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cupe.on.ca\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cupe.on.ca\/fr\/wp-json\/wp\/v2\/users\/21"}],"replies":[{"embeddable":true,"href":"https:\/\/cupe.on.ca\/fr\/wp-json\/wp\/v2\/comments?post=59510"}],"version-history":[{"count":0,"href":"https:\/\/cupe.on.ca\/fr\/wp-json\/wp\/v2\/posts\/59510\/revisions"}],"wp:attachment":[{"href":"https:\/\/cupe.on.ca\/fr\/wp-json\/wp\/v2\/media?parent=59510"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cupe.on.ca\/fr\/wp-json\/wp\/v2\/categories?post=59510"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cupe.on.ca\/fr\/wp-json\/wp\/v2\/tags?post=59510"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}