






{"id":59362,"date":"2025-06-04T09:20:02","date_gmt":"2025-06-04T13:20:02","guid":{"rendered":"https:\/\/cupe.on.ca\/strike-at-wsib-stretches-as-employer-dawdles\/"},"modified":"2025-06-05T09:51:51","modified_gmt":"2025-06-05T13:51:51","slug":"strike-at-wsib-stretches-as-employer-dawdles","status":"publish","type":"post","link":"https:\/\/cupe.on.ca\/fr\/strike-at-wsib-stretches-as-employer-dawdles\/","title":{"rendered":"La gr\u00e8ve \u00e0 la CSPAAT s\u2019\u00e9tire en raison de l\u2019inaction de l\u2019employeur"},"content":{"rendered":"<div id=\"main-content\" class=\"u-2-3\" role=\"main\">\n<div class=\"ds-1col node node-basic-page cupe-ia-news view-mode-full clearfix\">\n<div class=\"field field-name-body field-type-text-with-summary\">\n<p>La direction de la CSPAAT tarde \u00e0 d\u00e9livrer un laissez-passer alors qu\u2019approche la deuxi\u00e8me semaine de lock-out. L\u2019\u00e9quipe de n\u00e9gociation du SCFP\u00a01750-OCEU a pr\u00e9sent\u00e9 une contre-proposition compl\u00e8te \u00e0 l\u2019employeur le 1<sup>er<\/sup>\u00a0juin, mais une r\u00e9ponse exhaustive se fait\u00a0attendre.<\/p>\n<p>\u00ab\u00a0C\u2019est comme si l\u2019employeur ne prenait pas cette gr\u00e8ve au s\u00e9rieux. Nos membres font du piquetage \u00e0 cause de la surcharge de travail et du manque de respect de l\u2019employeur, mais ces man\u0153uvres dilatoires sont juste un autre signe de m\u00e9pris\u00a0\u00bb, affirme Harry\u00a0Goslin, pr\u00e9sident du\u00a0SCFP\u00a01750-OCEU.<\/p>\n<p>\u00ab\u00a0L\u2019employeur a fait attendre le syndicat quatre\u00a0jours pour un laissez-passer la semaine derni\u00e8re. Cette absence d\u2019engagement r\u00e9el dans le processus est profond\u00e9ment frustrante\u00a0\u00bb, explique Nicole\u00a0Francis, d\u00e9l\u00e9gu\u00e9e principale du\u00a0SCFP\u00a01750-OCEU.<\/p>\n<p>Le syndicat esp\u00e8re arriver \u00e0 une solution concr\u00e8te \u00e0 la surcharge de travail, qui entra\u00eene un taux \u00e9lev\u00e9 d\u2019\u00e9puisement professionnel et de cong\u00e9s de maladie au sein des travailleuses et travailleurs, ainsi qu\u2019\u00e0 une entente qui permettra aux membres de retrouver leur pouvoir d\u2019achat d\u2019avant le gel des salaires initi\u00e9 par le projet de loi\u00a0C-124.<\/p>\n<p>\u00ab\u00a0On nous a dit que le Conseil du Tr\u00e9sor a conseill\u00e9 \u00e0 l\u2019employeur de ne pas nous accorder une entente salariale \u00e9quitable, dit Harry\u00a0Goslin. On ne comprend pas pourquoi le Conseil du Tr\u00e9sor s\u2019en m\u00eale, puisque la CSPAAT n\u2019est pas financ\u00e9e par les\u00a0contribuables.\u00a0\u00bb<\/p>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>La direction de la CSPAAT tarde \u00e0 d\u00e9livrer un laissez-passer alors qu\u2019approche la deuxi\u00e8me semaine de lock-out. L\u2019\u00e9quipe de n\u00e9gociation du SCFP\u00a01750-OCEU a pr\u00e9sent\u00e9 une contre-proposition compl\u00e8te \u00e0 l\u2019employeur le 1er\u00a0juin, mais une r\u00e9ponse exhaustive se fait\u00a0attendre. \u00ab\u00a0C\u2019est comme si l\u2019employeur ne prenait pas cette gr\u00e8ve au s\u00e9rieux. Nos membres font du piquetage \u00e0 cause&hellip;<\/p>\n","protected":false},"author":21,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[247,260],"tags":[],"class_list":["post-59362","post","type-post","status-publish","format-standard","hentry","category-la-solidarite","category-strikesupport-fr","category-247","category-260","description-off"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La gr\u00e8ve \u00e0 la CSPAAT s\u2019\u00e9tire en raison de l\u2019inaction de l\u2019employeur - SCFP-Ontario<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cupe.on.ca\/fr\/strike-at-wsib-stretches-as-employer-dawdles\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La gr\u00e8ve \u00e0 la CSPAAT s\u2019\u00e9tire en raison de l\u2019inaction de l\u2019employeur - SCFP-Ontario\" \/>\n<meta property=\"og:description\" content=\"La direction de la CSPAAT tarde \u00e0 d\u00e9livrer un laissez-passer alors qu\u2019approche la deuxi\u00e8me semaine de lock-out. L\u2019\u00e9quipe de n\u00e9gociation du SCFP\u00a01750-OCEU a pr\u00e9sent\u00e9 une contre-proposition compl\u00e8te \u00e0 l\u2019employeur le 1er\u00a0juin, mais une r\u00e9ponse exhaustive se fait\u00a0attendre. \u00ab\u00a0C\u2019est comme si l\u2019employeur ne prenait pas cette gr\u00e8ve au s\u00e9rieux. Nos membres font du piquetage \u00e0 cause&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cupe.on.ca\/fr\/strike-at-wsib-stretches-as-employer-dawdles\/\" \/>\n<meta property=\"og:site_name\" content=\"SCFP-Ontario\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/CUPEOntario\" \/>\n<meta property=\"article:published_time\" content=\"2025-06-04T13:20:02+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-06-05T13:51:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cupe.on.ca\/wp-content\/uploads\/2020\/09\/cupetwitter2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Alisha Sharma\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@CUPEOntario\" \/>\n<meta name=\"twitter:site\" content=\"@CUPEOntario\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/cupe.on.ca\\\/fr\\\/strike-at-wsib-stretches-as-employer-dawdles\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cupe.on.ca\\\/fr\\\/strike-at-wsib-stretches-as-employer-dawdles\\\/\"},\"author\":{\"name\":\"Alisha Sharma\",\"@id\":\"https:\\\/\\\/cupe.on.ca\\\/fr\\\/#\\\/schema\\\/person\\\/0a67c9ec31b14c86d26e95dc2a13e3dc\"},\"headline\":\"La gr\u00e8ve \u00e0 la CSPAAT s\u2019\u00e9tire en raison de l\u2019inaction de l\u2019employeur\",\"datePublished\":\"2025-06-04T13:20:02+00:00\",\"dateModified\":\"2025-06-05T13:51:51+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/cupe.on.ca\\\/fr\\\/strike-at-wsib-stretches-as-employer-dawdles\\\/\"},\"wordCount\":269,\"articleSection\":[\"La solidarit\u00e9\",\"Strike Support\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/cupe.on.ca\\\/fr\\\/strike-at-wsib-stretches-as-employer-dawdles\\\/\",\"url\":\"https:\\\/\\\/cupe.on.ca\\\/fr\\\/strike-at-wsib-stretches-as-employer-dawdles\\\/\",\"name\":\"La gr\u00e8ve \u00e0 la CSPAAT s\u2019\u00e9tire en raison de l\u2019inaction de l\u2019employeur - SCFP-Ontario\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cupe.on.ca\\\/fr\\\/#website\"},\"datePublished\":\"2025-06-04T13:20:02+00:00\",\"dateModified\":\"2025-06-05T13:51:51+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/cupe.on.ca\\\/fr\\\/#\\\/schema\\\/person\\\/0a67c9ec31b14c86d26e95dc2a13e3dc\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/cupe.on.ca\\\/fr\\\/strike-at-wsib-stretches-as-employer-dawdles\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/cupe.on.ca\\\/fr\\\/strike-at-wsib-stretches-as-employer-dawdles\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/cupe.on.ca\\\/fr\\\/strike-at-wsib-stretches-as-employer-dawdles\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/cupe.on.ca\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La gr\u00e8ve \u00e0 la CSPAAT s\u2019\u00e9tire en raison de l\u2019inaction de l\u2019employeur\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cupe.on.ca\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/cupe.on.ca\\\/fr\\\/\",\"name\":\"SCFP-Ontario\",\"description\":\"B\u00e2tir Un Ontario Meilleur\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/cupe.on.ca\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/cupe.on.ca\\\/fr\\\/#\\\/schema\\\/person\\\/0a67c9ec31b14c86d26e95dc2a13e3dc\",\"name\":\"Alisha Sharma\",\"url\":\"https:\\\/\\\/cupe.on.ca\\\/fr\\\/author\\\/asharmacupe-on-ca\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La gr\u00e8ve \u00e0 la CSPAAT s\u2019\u00e9tire en raison de l\u2019inaction de l\u2019employeur - SCFP-Ontario","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cupe.on.ca\/fr\/strike-at-wsib-stretches-as-employer-dawdles\/","og_locale":"fr_FR","og_type":"article","og_title":"La gr\u00e8ve \u00e0 la CSPAAT s\u2019\u00e9tire en raison de l\u2019inaction de l\u2019employeur - SCFP-Ontario","og_description":"La direction de la CSPAAT tarde \u00e0 d\u00e9livrer un laissez-passer alors qu\u2019approche la deuxi\u00e8me semaine de lock-out. L\u2019\u00e9quipe de n\u00e9gociation du SCFP\u00a01750-OCEU a pr\u00e9sent\u00e9 une contre-proposition compl\u00e8te \u00e0 l\u2019employeur le 1er\u00a0juin, mais une r\u00e9ponse exhaustive se fait\u00a0attendre. \u00ab\u00a0C\u2019est comme si l\u2019employeur ne prenait pas cette gr\u00e8ve au s\u00e9rieux. Nos membres font du piquetage \u00e0 cause&hellip;","og_url":"https:\/\/cupe.on.ca\/fr\/strike-at-wsib-stretches-as-employer-dawdles\/","og_site_name":"SCFP-Ontario","article_publisher":"https:\/\/facebook.com\/CUPEOntario","article_published_time":"2025-06-04T13:20:02+00:00","article_modified_time":"2025-06-05T13:51:51+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/cupe.on.ca\/wp-content\/uploads\/2020\/09\/cupetwitter2.jpg","type":"image\/jpeg"}],"author":"Alisha Sharma","twitter_card":"summary_large_image","twitter_creator":"@CUPEOntario","twitter_site":"@CUPEOntario","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/cupe.on.ca\/fr\/strike-at-wsib-stretches-as-employer-dawdles\/#article","isPartOf":{"@id":"https:\/\/cupe.on.ca\/fr\/strike-at-wsib-stretches-as-employer-dawdles\/"},"author":{"name":"Alisha Sharma","@id":"https:\/\/cupe.on.ca\/fr\/#\/schema\/person\/0a67c9ec31b14c86d26e95dc2a13e3dc"},"headline":"La gr\u00e8ve \u00e0 la CSPAAT s\u2019\u00e9tire en raison de l\u2019inaction de l\u2019employeur","datePublished":"2025-06-04T13:20:02+00:00","dateModified":"2025-06-05T13:51:51+00:00","mainEntityOfPage":{"@id":"https:\/\/cupe.on.ca\/fr\/strike-at-wsib-stretches-as-employer-dawdles\/"},"wordCount":269,"articleSection":["La solidarit\u00e9","Strike Support"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/cupe.on.ca\/fr\/strike-at-wsib-stretches-as-employer-dawdles\/","url":"https:\/\/cupe.on.ca\/fr\/strike-at-wsib-stretches-as-employer-dawdles\/","name":"La gr\u00e8ve \u00e0 la CSPAAT s\u2019\u00e9tire en raison de l\u2019inaction de l\u2019employeur - SCFP-Ontario","isPartOf":{"@id":"https:\/\/cupe.on.ca\/fr\/#website"},"datePublished":"2025-06-04T13:20:02+00:00","dateModified":"2025-06-05T13:51:51+00:00","author":{"@id":"https:\/\/cupe.on.ca\/fr\/#\/schema\/person\/0a67c9ec31b14c86d26e95dc2a13e3dc"},"breadcrumb":{"@id":"https:\/\/cupe.on.ca\/fr\/strike-at-wsib-stretches-as-employer-dawdles\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cupe.on.ca\/fr\/strike-at-wsib-stretches-as-employer-dawdles\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/cupe.on.ca\/fr\/strike-at-wsib-stretches-as-employer-dawdles\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/cupe.on.ca\/fr\/"},{"@type":"ListItem","position":2,"name":"La gr\u00e8ve \u00e0 la CSPAAT s\u2019\u00e9tire en raison de l\u2019inaction de l\u2019employeur"}]},{"@type":"WebSite","@id":"https:\/\/cupe.on.ca\/fr\/#website","url":"https:\/\/cupe.on.ca\/fr\/","name":"SCFP-Ontario","description":"B\u00e2tir Un Ontario Meilleur","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cupe.on.ca\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/cupe.on.ca\/fr\/#\/schema\/person\/0a67c9ec31b14c86d26e95dc2a13e3dc","name":"Alisha Sharma","url":"https:\/\/cupe.on.ca\/fr\/author\/asharmacupe-on-ca\/"}]}},"_links":{"self":[{"href":"https:\/\/cupe.on.ca\/fr\/wp-json\/wp\/v2\/posts\/59362","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cupe.on.ca\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cupe.on.ca\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cupe.on.ca\/fr\/wp-json\/wp\/v2\/users\/21"}],"replies":[{"embeddable":true,"href":"https:\/\/cupe.on.ca\/fr\/wp-json\/wp\/v2\/comments?post=59362"}],"version-history":[{"count":0,"href":"https:\/\/cupe.on.ca\/fr\/wp-json\/wp\/v2\/posts\/59362\/revisions"}],"wp:attachment":[{"href":"https:\/\/cupe.on.ca\/fr\/wp-json\/wp\/v2\/media?parent=59362"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cupe.on.ca\/fr\/wp-json\/wp\/v2\/categories?post=59362"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cupe.on.ca\/fr\/wp-json\/wp\/v2\/tags?post=59362"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}