






{"id":54110,"date":"2024-02-22T12:30:54","date_gmt":"2024-02-22T17:30:54","guid":{"rendered":"https:\/\/cupe.on.ca\/?p=54110"},"modified":"2024-02-22T17:18:37","modified_gmt":"2024-02-22T22:18:37","slug":"labrogation-de-la-loi-124-le-retablissement-des-salaires-voles-et-les-excuses-aux-travailleurs-du-secteur-public-doivent-etre-des-priorites-pour-les-pc-de-ford","status":"publish","type":"post","link":"https:\/\/cupe.on.ca\/fr\/labrogation-de-la-loi-124-le-retablissement-des-salaires-voles-et-les-excuses-aux-travailleurs-du-secteur-public-doivent-etre-des-priorites-pour-les-pc-de-ford\/","title":{"rendered":"L&rsquo;abrogation de la loi 124, le r\u00e9tablissement des salaires vol\u00e9s et les excuses aux travailleurs du secteur public doivent \u00eatre des priorit\u00e9s pour les PC de Ford."},"content":{"rendered":"<p style=\"text-align: justify;\"><strong>TORONTO<\/strong> &#8211; Le SCFP Ontario demande aux conservateurs de Ford de commencer la session l\u00e9gislative du printemps en abrogeant le projet de loi 124 et en s&rsquo;assurant que leur budget provincial de mars contienne le financement d&rsquo;un recours pour r\u00e9tablir les millions de dollars de salaires perdus par les travailleurs du secteur public lorsque le projet de loi 124 \u00e9tait en vigueur.<br \/>\nLe syndicat se fait \u00e9galement l&rsquo;\u00e9cho de l&rsquo;appel lanc\u00e9 par Marit Stiles, chef du Parti n\u00e9o-d\u00e9mocrate de l&rsquo;Ontario, qui a demand\u00e9 que des excuses soient pr\u00e9sent\u00e9es aux Ontariens pour les multiples crises cr\u00e9\u00e9es par le projet de loi 124.<br \/>\n\u00ab Doug Ford compte nous distraire avec des absurdit\u00e9s sur le fait de \u00ab faire avancer les choses \u00bb et agit comme si nous \u00e9tions tous amn\u00e9siques au sujet du projet de loi 124. Eh bien, ce n&rsquo;est pas le cas. Et nous ne le laisserons pas s&rsquo;en tirer en pr\u00e9tendant que le projet de loi 124 n&rsquo;a jamais exist\u00e9, ou que ses cons\u00e9quences ont \u00e9t\u00e9 rien de moins que d\u00e9sastreuses pour les habitants de cette province. L&rsquo;abrogation de ce projet de loi aurait d\u00fb \u00eatre le tout premier point \u00e0 l&rsquo;ordre du jour lors de la reprise des travaux de la l\u00e9gislature cette semaine \u00bb, a d\u00e9clar\u00e9 Fred Hahn, pr\u00e9sident du SCFP de l&rsquo;Ontario.<br \/>\nLes conservateurs ont promis d&rsquo;abroger la loi 124, qui supprime les salaires, le lendemain du jour o\u00f9 ils ont perdu leur appel de la d\u00e9cision de la Cour sup\u00e9rieure de 2022 qui d\u00e9clarait la loi inconstitutionnelle. Le rejet de l&rsquo;appel de la semaine derni\u00e8re signifie que deux tribunaux de l&rsquo;Ontario ont maintenant confirm\u00e9 que la loi violait la constitution.<br \/>\n\u00ab \u00c0 cause de la loi 124, plus d&rsquo;un million de travailleurs du secteur public &#8211; dont beaucoup de femmes, beaucoup de personnes racialis\u00e9es et beaucoup de bas salaires &#8211; ont \u00e9t\u00e9 priv\u00e9s de la possibilit\u00e9 de n\u00e9gocier de meilleurs salaires et de meilleures conditions de travail. Cette loi a viol\u00e9 leurs droits et a caus\u00e9 des dommages incalculables aux services publics de l&rsquo;Ontario \u00bb, a d\u00e9clar\u00e9 M. Hahn.<br \/>\nLa loi 124 a limit\u00e9 les augmentations salariales dans le secteur public \u00e0 1 % pour quelque 1,3 million de travailleurs de la fonction publique territoriale, soit 1 travailleur ontarien sur 6. Le Bureau de la Responsabilit\u00e9 Financi\u00e8re de l&rsquo;Ontario a estim\u00e9 que la loi les a priv\u00e9s d&rsquo;un montant collectif de 2,1 milliards de dollars en salaires.<br \/>\nLe SCFP Ontario et d&rsquo;autres syndicats consid\u00e8rent que la loi 124 est en grande partie responsable de la p\u00e9nurie actuelle de travailleurs dans les secteurs des soins, car les bas salaires ont rendu presque impossible pour les employeurs du secteur public &#8211; y compris les h\u00f4pitaux, les maisons de soins de longue dur\u00e9e, les universit\u00e9s, les agences de services sociaux, les \u00e9coles et les centres de garde d&rsquo;enfants &#8211; de recruter et de conserver du personnel. La loi a \u00e9galement contribu\u00e9 au manque de personnel et \u00e0 des niveaux \u00e9lev\u00e9s d&rsquo;\u00e9puisement professionnel parmi les travailleurs de premi\u00e8re ligne.<br \/>\n\u00ab Chaque membre du groupe parlementaire conservateur a vot\u00e9 en faveur d&rsquo;une l\u00e9gislation qui s&rsquo;est av\u00e9r\u00e9e violer des droits prot\u00e9g\u00e9s par la Constitution. Leur priorit\u00e9 devrait \u00eatre de rectifier le tir. Mais leur m\u00e9pris pour les travailleurs, pour les services publics dont d\u00e9pendent nos communaut\u00e9s et pour les Ontariens signifie qu&rsquo;ils ne le feront pas, \u00e0 moins que la pression publique et politique ne les contraigne \u00e0 agir \u00bb.<br \/>\nLes conservateurs ne manquent jamais de moyens pour montrer leur m\u00e9pris pour le secteur public, a d\u00e9clar\u00e9 M. Hahn, soulignant qu\u2019 \u00ab ils construisent des h\u00f4pitaux priv\u00e9s, les travailleurs de l&rsquo;\u00e9ducation sont licenci\u00e9s parce que les \u00e9coles ont \u00e9t\u00e9 d\u00e9faites, ils ont sous-trait\u00e9 les points de vente de ServiceOntario \u00e0 Staples, et ont donn\u00e9 l&rsquo;espace public de la Place de l&rsquo;Ontario \u00e0 une station thermale priv\u00e9e \u00bb.<br \/>\n\u00ab Mais nous ne permettrons pas aux conservateurs d&rsquo;oublier le mal qu&rsquo;ils ont fait avec le projet de loi 124. Ils doivent prendre des mesures pour abroger d\u00e9finitivement ce projet de loi. Ils doivent ensuite s&rsquo;assurer que le budget qu&rsquo;ils pr\u00e9senteront rectifie pleinement la situation qu&rsquo;ils ont cr\u00e9\u00e9e, qu&rsquo;il assure le financement int\u00e9gral des services et qu&rsquo;il offre une solution qui permette \u00e0 tous les travailleurs touch\u00e9s d&rsquo;\u00eatre indemnis\u00e9s \u00bb.<\/p>\n<p style=\"text-align: center;\">&#8211; 30 &#8211;<\/p>\n<p style=\"text-align: left;\">Pour plus d&rsquo;informations :<br \/>\nMary Unan, SCFP Communications | 647-390-9839 | munan@cupe.ca<\/p>\n<h6 style=\"text-align: left;\">PC\/COPE491<\/h6>\n","protected":false},"excerpt":{"rendered":"<p>TORONTO &#8211; Le SCFP Ontario demande aux conservateurs de Ford de commencer la session l\u00e9gislative du printemps en abrogeant le projet de loi 124 et en s&rsquo;assurant que leur budget provincial de mars contienne le financement d&rsquo;un recours pour r\u00e9tablir les millions de dollars de salaires perdus par les travailleurs du secteur public lorsque le&hellip;<\/p>\n","protected":false},"author":24,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[247],"tags":[],"class_list":["post-54110","post","type-post","status-publish","format-standard","hentry","category-la-solidarite","category-247","description-off"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>L&#039;abrogation de la loi 124, le r\u00e9tablissement des salaires vol\u00e9s et les excuses aux travailleurs du secteur public doivent \u00eatre des priorit\u00e9s pour les PC de Ford. - SCFP-Ontario<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cupe.on.ca\/fr\/labrogation-de-la-loi-124-le-retablissement-des-salaires-voles-et-les-excuses-aux-travailleurs-du-secteur-public-doivent-etre-des-priorites-pour-les-pc-de-ford\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"L&#039;abrogation de la loi 124, le r\u00e9tablissement des salaires vol\u00e9s et les excuses aux travailleurs du secteur public doivent \u00eatre des priorit\u00e9s pour les PC de Ford. - SCFP-Ontario\" \/>\n<meta property=\"og:description\" content=\"TORONTO &#8211; Le SCFP Ontario demande aux conservateurs de Ford de commencer la session l\u00e9gislative du printemps en abrogeant le projet de loi 124 et en s&rsquo;assurant que leur budget provincial de mars contienne le financement d&rsquo;un recours pour r\u00e9tablir les millions de dollars de salaires perdus par les travailleurs du secteur public lorsque le&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cupe.on.ca\/fr\/labrogation-de-la-loi-124-le-retablissement-des-salaires-voles-et-les-excuses-aux-travailleurs-du-secteur-public-doivent-etre-des-priorites-pour-les-pc-de-ford\/\" \/>\n<meta property=\"og:site_name\" content=\"SCFP-Ontario\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/CUPEOntario\" \/>\n<meta property=\"article:published_time\" content=\"2024-02-22T17:30:54+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-02-22T22:18:37+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cupe.on.ca\/wp-content\/uploads\/2020\/09\/cupetwitter2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Maryant Perez\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@CUPEOntario\" \/>\n<meta name=\"twitter:site\" content=\"@CUPEOntario\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/cupe.on.ca\\\/fr\\\/labrogation-de-la-loi-124-le-retablissement-des-salaires-voles-et-les-excuses-aux-travailleurs-du-secteur-public-doivent-etre-des-priorites-pour-les-pc-de-ford\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cupe.on.ca\\\/fr\\\/labrogation-de-la-loi-124-le-retablissement-des-salaires-voles-et-les-excuses-aux-travailleurs-du-secteur-public-doivent-etre-des-priorites-pour-les-pc-de-ford\\\/\"},\"author\":{\"name\":\"Maryant Perez\",\"@id\":\"https:\\\/\\\/cupe.on.ca\\\/fr\\\/#\\\/schema\\\/person\\\/941ebc85fcf3edd16e60db7b4d9a4c80\"},\"headline\":\"L&rsquo;abrogation de la loi 124, le r\u00e9tablissement des salaires vol\u00e9s et les excuses aux travailleurs du secteur public doivent \u00eatre des priorit\u00e9s pour les PC de Ford.\",\"datePublished\":\"2024-02-22T17:30:54+00:00\",\"dateModified\":\"2024-02-22T22:18:37+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/cupe.on.ca\\\/fr\\\/labrogation-de-la-loi-124-le-retablissement-des-salaires-voles-et-les-excuses-aux-travailleurs-du-secteur-public-doivent-etre-des-priorites-pour-les-pc-de-ford\\\/\"},\"wordCount\":770,\"articleSection\":[\"La solidarit\u00e9\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/cupe.on.ca\\\/fr\\\/labrogation-de-la-loi-124-le-retablissement-des-salaires-voles-et-les-excuses-aux-travailleurs-du-secteur-public-doivent-etre-des-priorites-pour-les-pc-de-ford\\\/\",\"url\":\"https:\\\/\\\/cupe.on.ca\\\/fr\\\/labrogation-de-la-loi-124-le-retablissement-des-salaires-voles-et-les-excuses-aux-travailleurs-du-secteur-public-doivent-etre-des-priorites-pour-les-pc-de-ford\\\/\",\"name\":\"L'abrogation de la loi 124, le r\u00e9tablissement des salaires vol\u00e9s et les excuses aux travailleurs du secteur public doivent \u00eatre des priorit\u00e9s pour les PC de Ford. - SCFP-Ontario\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cupe.on.ca\\\/fr\\\/#website\"},\"datePublished\":\"2024-02-22T17:30:54+00:00\",\"dateModified\":\"2024-02-22T22:18:37+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/cupe.on.ca\\\/fr\\\/#\\\/schema\\\/person\\\/941ebc85fcf3edd16e60db7b4d9a4c80\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/cupe.on.ca\\\/fr\\\/labrogation-de-la-loi-124-le-retablissement-des-salaires-voles-et-les-excuses-aux-travailleurs-du-secteur-public-doivent-etre-des-priorites-pour-les-pc-de-ford\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/cupe.on.ca\\\/fr\\\/labrogation-de-la-loi-124-le-retablissement-des-salaires-voles-et-les-excuses-aux-travailleurs-du-secteur-public-doivent-etre-des-priorites-pour-les-pc-de-ford\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/cupe.on.ca\\\/fr\\\/labrogation-de-la-loi-124-le-retablissement-des-salaires-voles-et-les-excuses-aux-travailleurs-du-secteur-public-doivent-etre-des-priorites-pour-les-pc-de-ford\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/cupe.on.ca\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"L&#8217;abrogation de la loi 124, le r\u00e9tablissement des salaires vol\u00e9s et les excuses aux travailleurs du secteur public doivent \u00eatre des priorit\u00e9s pour les PC de Ford.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cupe.on.ca\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/cupe.on.ca\\\/fr\\\/\",\"name\":\"SCFP-Ontario\",\"description\":\"B\u00e2tir Un Ontario Meilleur\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/cupe.on.ca\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/cupe.on.ca\\\/fr\\\/#\\\/schema\\\/person\\\/941ebc85fcf3edd16e60db7b4d9a4c80\",\"name\":\"Maryant Perez\",\"url\":\"https:\\\/\\\/cupe.on.ca\\\/fr\\\/author\\\/mperez\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"L'abrogation de la loi 124, le r\u00e9tablissement des salaires vol\u00e9s et les excuses aux travailleurs du secteur public doivent \u00eatre des priorit\u00e9s pour les PC de Ford. - SCFP-Ontario","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cupe.on.ca\/fr\/labrogation-de-la-loi-124-le-retablissement-des-salaires-voles-et-les-excuses-aux-travailleurs-du-secteur-public-doivent-etre-des-priorites-pour-les-pc-de-ford\/","og_locale":"fr_FR","og_type":"article","og_title":"L'abrogation de la loi 124, le r\u00e9tablissement des salaires vol\u00e9s et les excuses aux travailleurs du secteur public doivent \u00eatre des priorit\u00e9s pour les PC de Ford. - SCFP-Ontario","og_description":"TORONTO &#8211; Le SCFP Ontario demande aux conservateurs de Ford de commencer la session l\u00e9gislative du printemps en abrogeant le projet de loi 124 et en s&rsquo;assurant que leur budget provincial de mars contienne le financement d&rsquo;un recours pour r\u00e9tablir les millions de dollars de salaires perdus par les travailleurs du secteur public lorsque le&hellip;","og_url":"https:\/\/cupe.on.ca\/fr\/labrogation-de-la-loi-124-le-retablissement-des-salaires-voles-et-les-excuses-aux-travailleurs-du-secteur-public-doivent-etre-des-priorites-pour-les-pc-de-ford\/","og_site_name":"SCFP-Ontario","article_publisher":"https:\/\/facebook.com\/CUPEOntario","article_published_time":"2024-02-22T17:30:54+00:00","article_modified_time":"2024-02-22T22:18:37+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/cupe.on.ca\/wp-content\/uploads\/2020\/09\/cupetwitter2.jpg","type":"image\/jpeg"}],"author":"Maryant Perez","twitter_card":"summary_large_image","twitter_creator":"@CUPEOntario","twitter_site":"@CUPEOntario","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/cupe.on.ca\/fr\/labrogation-de-la-loi-124-le-retablissement-des-salaires-voles-et-les-excuses-aux-travailleurs-du-secteur-public-doivent-etre-des-priorites-pour-les-pc-de-ford\/#article","isPartOf":{"@id":"https:\/\/cupe.on.ca\/fr\/labrogation-de-la-loi-124-le-retablissement-des-salaires-voles-et-les-excuses-aux-travailleurs-du-secteur-public-doivent-etre-des-priorites-pour-les-pc-de-ford\/"},"author":{"name":"Maryant Perez","@id":"https:\/\/cupe.on.ca\/fr\/#\/schema\/person\/941ebc85fcf3edd16e60db7b4d9a4c80"},"headline":"L&rsquo;abrogation de la loi 124, le r\u00e9tablissement des salaires vol\u00e9s et les excuses aux travailleurs du secteur public doivent \u00eatre des priorit\u00e9s pour les PC de Ford.","datePublished":"2024-02-22T17:30:54+00:00","dateModified":"2024-02-22T22:18:37+00:00","mainEntityOfPage":{"@id":"https:\/\/cupe.on.ca\/fr\/labrogation-de-la-loi-124-le-retablissement-des-salaires-voles-et-les-excuses-aux-travailleurs-du-secteur-public-doivent-etre-des-priorites-pour-les-pc-de-ford\/"},"wordCount":770,"articleSection":["La solidarit\u00e9"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/cupe.on.ca\/fr\/labrogation-de-la-loi-124-le-retablissement-des-salaires-voles-et-les-excuses-aux-travailleurs-du-secteur-public-doivent-etre-des-priorites-pour-les-pc-de-ford\/","url":"https:\/\/cupe.on.ca\/fr\/labrogation-de-la-loi-124-le-retablissement-des-salaires-voles-et-les-excuses-aux-travailleurs-du-secteur-public-doivent-etre-des-priorites-pour-les-pc-de-ford\/","name":"L'abrogation de la loi 124, le r\u00e9tablissement des salaires vol\u00e9s et les excuses aux travailleurs du secteur public doivent \u00eatre des priorit\u00e9s pour les PC de Ford. - SCFP-Ontario","isPartOf":{"@id":"https:\/\/cupe.on.ca\/fr\/#website"},"datePublished":"2024-02-22T17:30:54+00:00","dateModified":"2024-02-22T22:18:37+00:00","author":{"@id":"https:\/\/cupe.on.ca\/fr\/#\/schema\/person\/941ebc85fcf3edd16e60db7b4d9a4c80"},"breadcrumb":{"@id":"https:\/\/cupe.on.ca\/fr\/labrogation-de-la-loi-124-le-retablissement-des-salaires-voles-et-les-excuses-aux-travailleurs-du-secteur-public-doivent-etre-des-priorites-pour-les-pc-de-ford\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cupe.on.ca\/fr\/labrogation-de-la-loi-124-le-retablissement-des-salaires-voles-et-les-excuses-aux-travailleurs-du-secteur-public-doivent-etre-des-priorites-pour-les-pc-de-ford\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/cupe.on.ca\/fr\/labrogation-de-la-loi-124-le-retablissement-des-salaires-voles-et-les-excuses-aux-travailleurs-du-secteur-public-doivent-etre-des-priorites-pour-les-pc-de-ford\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/cupe.on.ca\/fr\/"},{"@type":"ListItem","position":2,"name":"L&#8217;abrogation de la loi 124, le r\u00e9tablissement des salaires vol\u00e9s et les excuses aux travailleurs du secteur public doivent \u00eatre des priorit\u00e9s pour les PC de Ford."}]},{"@type":"WebSite","@id":"https:\/\/cupe.on.ca\/fr\/#website","url":"https:\/\/cupe.on.ca\/fr\/","name":"SCFP-Ontario","description":"B\u00e2tir Un Ontario Meilleur","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cupe.on.ca\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/cupe.on.ca\/fr\/#\/schema\/person\/941ebc85fcf3edd16e60db7b4d9a4c80","name":"Maryant Perez","url":"https:\/\/cupe.on.ca\/fr\/author\/mperez\/"}]}},"_links":{"self":[{"href":"https:\/\/cupe.on.ca\/fr\/wp-json\/wp\/v2\/posts\/54110","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cupe.on.ca\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cupe.on.ca\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cupe.on.ca\/fr\/wp-json\/wp\/v2\/users\/24"}],"replies":[{"embeddable":true,"href":"https:\/\/cupe.on.ca\/fr\/wp-json\/wp\/v2\/comments?post=54110"}],"version-history":[{"count":0,"href":"https:\/\/cupe.on.ca\/fr\/wp-json\/wp\/v2\/posts\/54110\/revisions"}],"wp:attachment":[{"href":"https:\/\/cupe.on.ca\/fr\/wp-json\/wp\/v2\/media?parent=54110"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cupe.on.ca\/fr\/wp-json\/wp\/v2\/categories?post=54110"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cupe.on.ca\/fr\/wp-json\/wp\/v2\/tags?post=54110"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}