






{"id":40835,"date":"2021-03-26T10:53:47","date_gmt":"2021-03-26T14:53:47","guid":{"rendered":"https:\/\/cupe.on.ca\/for-a-university-sector-in-crisis-ford-conservatives-2021-budget-a-shocking-dereliction-of-responsibility-says-cupe-ontarios-university-workers-chair\/"},"modified":"2021-03-29T10:56:46","modified_gmt":"2021-03-29T14:56:46","slug":"pour-le-secteur-universitaire-en-crise-le-budget-2021-des-conservateurs-de-ford-represente-une-negligence-crasse-de-ses-devoirs-selon-le-president-du-secteur-universitaire-au-scfp-onta","status":"publish","type":"post","link":"https:\/\/cupe.on.ca\/fr\/pour-le-secteur-universitaire-en-crise-le-budget-2021-des-conservateurs-de-ford-represente-une-negligence-crasse-de-ses-devoirs-selon-le-president-du-secteur-universitaire-au-scfp-onta\/","title":{"rendered":"Pour le secteur universitaire en crise, le budget 2021 des conservateurs de Ford repr\u00e9sente une \u00ab n\u00e9gligence crasse de ses devoirs \u00bb, selon le pr\u00e9sident du secteur universitaire au SCFP-Ontario"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row][vc_column][vc_raw_html]JTNDZGl2JTIwY2xhc3MlM0QlMjJmYi1saWtlJTIyJTIwZGF0YS1ocmVmJTNEJTIyaHR0cHMlM0ElMkYlMkZmYWNlYm9vay5jb20lMkZjdXBlb250YXJpbyUyMiUyMGRhdGEtbGF5b3V0JTNEJTIyc3RhbmRhcmQlMjIlMjBkYXRhLWFjdGlvbiUzRCUyMmxpa2UlMjIlMjBkYXRhLXNpemUlM0QlMjJsYXJnZSUyMiUyMGRhdGEtc2hvdy1mYWNlcyUzRCUyMnRydWUlMjIlMjBkYXRhLXNoYXJlJTNEJTIyZmFsc2UlMjIlM0UlM0MlMkZkaXYlM0U=[\/vc_raw_html]<div class=\"ult-spacer spacer-6a57696f3ea02\" data-id=\"6a57696f3ea02\" data-height=\"10\" data-height-mobile=\"10\" data-height-tab=\"10\" data-height-tab-portrait=\"\" data-height-mobile-landscape=\"\" style=\"clear:both;display:block;\"><\/div>[vc_column_text]<strong>TORONTO (ONTARIO) <\/strong>\u2013\u00a0Le budget provincial d\u00e9pos\u00e9 hier par le ministre des Finances, Peter Bethlenfalvy, repr\u00e9sente une \u00ab\u00a0n\u00e9gligence crasse des devoirs\u00a0\u00bb du gouvernement conservateur Ford envers le secteur universitaire ontarien, selon David Simao, pr\u00e9sident du Comit\u00e9 de coordination des travailleurs universitaires de l\u2019Ontario (<span class=\"caps\">CCTUO<\/span>), qui parle au nom de plus de 30\u2009000 travailleurs universitaires repr\u00e9sent\u00e9s par le\u00a0<span class=\"caps\">SCFP<\/span>\u00a0dans toute la\u00a0province.<\/p>\n<p>\u00ab\u00a0M\u00eame dans une ann\u00e9e normale, le m\u00e9pris et l\u2019indiff\u00e9rence totale de ce budget \u00e0 l\u2019\u00e9gard de l\u2019enseignement postsecondaire se seraient d\u00e9marqu\u00e9s, ajoute-t-il. Mais, au milieu d\u2019une pand\u00e9mie mondiale qui ne survient qu\u2019une fois par si\u00e8cle, qui a mis en lumi\u00e8re tant de besoins critiques dans tous les secteurs de l\u2019\u00e9conomie ontarienne, il s\u2019agit d\u2019une n\u00e9gligence crasse des devoirs du ministre responsable des universit\u00e9s et de l\u2019ensemble du caucus conservateur de\u00a0Ford.\u00a0\u00bb<\/p>\n<p>Le budget d\u00e9pos\u00e9 hier poursuit la tendance aux coupes, en dollars r\u00e9els, dans le secteur universitaire. La subvention de fonctionnement de base de 3,6 milliards de dollars propos\u00e9e pour les 21 universit\u00e9s publiques de l\u2019Ontario dans le document budg\u00e9taire d\u2019hier ne parvient m\u00eame pas \u00e0 suivre l\u2019inflation. Ainsi, de mani\u00e8re concr\u00e8te, le montant que d\u00e9pense le provincial par \u00e9tudiant a diminu\u00e9 chaque ann\u00e9e sous le gouvernement conservateur de\u00a0Ford.<\/p>\n<p>En outre, l\u2019enveloppe de 700 millions de dollars annonc\u00e9e pour garnir les rangs des pr\u00e9pos\u00e9s aux services de soutien \u00e0 la personne (<span class=\"caps\">PSW<\/span>), afin d\u2019aider les Ontariens qui re\u00e7oivent des soins \u00e0 domicile ou qui vivent en \u00e9tablissement de soins de longue dur\u00e9e (<span class=\"caps\">SLD<\/span>), ne contient pas d\u2019argent frais. Les conservateurs de Ford ont plut\u00f4t d\u00e9tourn\u00e9 des fonds destin\u00e9s au R\u00e9gime d\u2019aide financi\u00e8re aux \u00e9tudiantes et \u00e9tudiants de l\u2019Ontario (<span class=\"caps\">RAFEO<\/span>) qui s\u2019adresse aux personnes qui poursuivent des \u00e9tudes\u00a0postsecondaires.<\/p>\n<p>\u00ab\u00a0Le discours sur le budget d\u2019hier du ministre Bethlenfalvy faisait pr\u00e8s de 6\u2009000 mots, mais un mot brillait par son absence\u00a0: \u00e0 aucun moment n\u2019y a-t-on entendu le mot universit\u00e9\u00a0\u00bb, d\u00e9plore Fred Hahn, pr\u00e9sident du\u00a0<span class=\"caps\">SCFP<\/span>-Ontario.<\/p>\n<p>\u00ab\u00a0C\u2019est comme si un pilier vital du d\u00e9veloppement socio\u00e9conomique de toute grande nation industrialis\u00e9e n\u2019existait pas aux yeux des plus hauts fonctionnaires du gouvernement conservateur Ford, ajoute-t-il. O\u00f9 le Cabinet pense-t-il que les m\u00e9decins, les infirmi\u00e8res, les chercheurs, les scientifiques, les experts en sant\u00e9 publique et d\u2019innombrables autres disciplines directement charg\u00e9es de lutter contre les pand\u00e9mies comme la\u00a0<span class=\"caps\">COVID<\/span>-19 re\u00e7oivent leur\u00a0formation\u00a0?\u00a0\u00bb<\/p>\n<p>Depuis leur arriv\u00e9e au pouvoir au d\u00e9but de l\u2019\u00e9t\u00e9\u00a02018, les conservateurs de Ford ont retranch\u00e9 des millions de dollars du secteur universitaire. En f\u00e9vrier dernier, l\u2019Universit\u00e9 Laurentienne de Sudbury a \u00e9t\u00e9 contrainte de se placer sous la protection de ses cr\u00e9anciers, pendant que les conservateurs de Ford ne faisaient rien pour garder solvable cette institution du Nord de\u00a0l\u2019Ontario.<\/p>\n<p>\u00ab\u00a0Un gouvernement qui ne prononce m\u00eame pas le mot universit\u00e9 dans son discours sur le budget n\u2019a rien \u00e0 offrir \u00e0 un secteur de l\u2019\u00e9conomie qui devrait \u00eatre \u00e0 l\u2019avant-garde pour aider la province \u00e0 sortir de cette pand\u00e9mie\u00a0\u00bb, estime Fred Hahn, qui a exhort\u00e9 \u00ab\u00a0tous les Ontariens soucieux de la qualit\u00e9 de l\u2019enseignement postsecondaire public \u00e0 se mobiliser et \u00e0 faire comprendre leur point de vue au\u00a0gouvernement.\u00a0\u00bb<\/p>\n<p>\u00ab\u00a0Ce budget ne fait rien pour aider l\u2019Universit\u00e9 Laurentienne, les \u00e9tudiants, les travailleurs universitaires ou le personnel de soutien des campus, rench\u00e9rit David Simao. Il ne s\u2019est m\u00eame pas donn\u00e9 la peine de d\u00e9biter des platitudes creuses. Par cons\u00e9quent, la t\u00e2che nous incombe \u00e0 tous de militer en faveur des universit\u00e9s avant que le gouvernement ne laisse ce secteur s\u2019enfoncer encore plus profond\u00e9ment dans la\u00a0crise.\u00a0\u00bb<\/p>\n<p>-30-<\/p>\n<p>Pour obtenir des renseignements suppl\u00e9mentaires, veuillez communiquer avec :<\/p>\n<p>David Simao, pr\u00e9sident du CCTUO, \u00e0 <a href=\"mailto:daviddsimao@gmail.com\">daviddsimao@gmail.com<\/a> ou au 613 668-9010<\/p>\n<p>Kevin Wilson, Service des communications du SCFP, \u00e0 <a href=\"mailto:kwilson@cupe.ca\">kwilson@cupe.ca<\/a>\u00a0ou au 416 821-6641<\/p>\n<p>lf\/sepb 491[\/vc_column_text]<div class=\"ult-spacer spacer-6a57696f3ea55\" data-id=\"6a57696f3ea55\" data-height=\"32\" data-height-mobile=\"32\" data-height-tab=\"32\" data-height-tab-portrait=\"\" data-height-mobile-landscape=\"\" style=\"clear:both;display:block;\"><\/div>[vc_separator]<div class=\"ult-spacer spacer-6a57696f3ea87\" data-id=\"6a57696f3ea87\" data-height=\"32\" data-height-mobile=\"32\" data-height-tab=\"32\" data-height-tab-portrait=\"\" data-height-mobile-landscape=\"\" style=\"clear:both;display:block;\"><\/div>[vc_column_text]<\/p>\n<h3>Inscrivez-vous pour recevoir des nouvelles du SCFP-Ontario.<\/h3>\n<p>[\/vc_column_text]<div class=\"ult-spacer spacer-6a57696f3eaaf\" data-id=\"6a57696f3eaaf\" data-height=\"32\" data-height-mobile=\"32\" data-height-tab=\"32\" data-height-tab-portrait=\"\" data-height-mobile-landscape=\"\" style=\"clear:both;display:block;\"><\/div>\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f30764-o1\" lang=\"en-CA\" dir=\"ltr\" data-wpcf7-id=\"30764\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/fr\/wp-json\/wp\/v2\/posts\/40835#wpcf7-f30764-o1\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"Contact form\" novalidate=\"novalidate\" data-status=\"init\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"30764\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.6\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"en_CA\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f30764-o1\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/><input type=\"hidden\" name=\"_wpcf7dtx_version\" value=\"5.0.6\" \/>\n<\/fieldset>\n<p>Votre nom au complet (champ obligatoire)<br \/>\n    <span class=\"wpcf7-form-control-wrap\" data-name=\"your-name\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"your-name\" \/><\/span> <\/p>\n\n<p>Votre courriel (champ obligatoire)<br \/>\n    <span class=\"wpcf7-form-control-wrap\" data-name=\"your-email\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"email\" name=\"your-email\" \/><\/span> <\/p>\n\n<p>\u00cates-vous membre du SCFP?<br \/>\n     <span class=\"wpcf7-form-control-wrap\" data-name=\"cupe-member\"><span class=\"wpcf7-form-control wpcf7-radio\"><span class=\"wpcf7-list-item first\"><input type=\"radio\" name=\"cupe-member\" value=\"Oui\" \/><span class=\"wpcf7-list-item-label\">Oui<\/span><\/span><span class=\"wpcf7-list-item last\"><input type=\"radio\" name=\"cupe-member\" value=\"Non\" checked=\"checked\" \/><span class=\"wpcf7-list-item-label\">Non<\/span><\/span><\/span><\/span> <\/p>\n\n<p>&nbsp;<\/p>\n\n<div class=\"cf7-cf-turnstile\" style=\"margin-top: 0px; margin-bottom: -15px;\"> <div id=\"cf-turnstile-cf7-3025765393\" class=\"cf-turnstile\" data-sitekey=\"0x4AAAAAACzoOn1JWbtRg9e1\" data-theme=\"light\" data-language=\"auto\" data-size=\"normal\" data-retry=\"auto\" data-retry-interval=\"1000\" data-refresh-expired=\"auto\" data-refresh-timeout=\"auto\" data-action=\"contact-form-7\" data-callback=\"turnstileCF7Callback\" data-appearance=\"always\"><\/div> <br class=\"cf-turnstile-br cf-turnstile-br-cf7-3025765393\"> <style>#cf-turnstile-cf7-3025765393 { margin-left: -15px; }<\/style> <script>document.addEventListener(\"DOMContentLoaded\",function(){document.querySelectorAll('.wpcf7-form').forEach(function(e){e.addEventListener('submit',function(){if(document.getElementById('cf-turnstile-cf7-3025765393')){setTimeout(function(){turnstile.reset('#cf-turnstile-cf7-3025765393');},1000)}})})});<\/script> <\/div><br\/><input class=\"wpcf7-form-control wpcf7-submit has-spinner\" type=\"submit\" value=\"Envoyer\" \/>\n\n<span class=\"wpcf7-form-control-wrap titleentry\" data-name=\"titleentry\"><input type=\"hidden\" name=\"titleentry\" class=\"wpcf7-form-control wpcf7-hidden wpcf7dtx wpcf7dtx-hidden\" aria-invalid=\"false\" value=\"Pour le secteur universitaire en crise, le budget 2021 des conservateurs de Ford repr\u00e9sente une \u00ab n\u00e9gligence crasse de ses devoirs \u00bb, selon le pr\u00e9sident du secteur universitaire au SCFP-Ontario\"><\/span><span class=\"wpcf7-form-control-wrap signup-title\" data-name=\"signup-title\"><input type=\"hidden\" name=\"signup-title\" id=\"idattrib\" class=\"wpcf7-form-control wpcf7-hidden wpcf7dtx wpcf7dtx-hidden classattrib\" aria-invalid=\"false\" value=\"SCFP Ontario\"><\/span><span class=\"wpcf7-form-control-wrap language\" data-name=\"language\"><input type=\"hidden\" name=\"language\" id=\"idattrib\" class=\"wpcf7-form-control wpcf7-hidden wpcf7dtx wpcf7dtx-hidden classattrib\" aria-invalid=\"false\" value=\"FR\"><\/span><span class=\"wpcf7-form-control-wrap image-url\" data-name=\"image-url\"><input type=\"hidden\" name=\"image-url\" id=\"idattrib\" class=\"wpcf7-form-control wpcf7-hidden wpcf7dtx wpcf7dtx-hidden classattrib\" aria-invalid=\"false\"><\/span><span class=\"wpcf7-form-control-wrap tags-to-add\" data-name=\"tags-to-add\"><input type=\"hidden\" name=\"tags-to-add\" id=\"idattrib\" class=\"wpcf7-form-control wpcf7-hidden wpcf7dtx wpcf7dtx-hidden classattrib\" aria-invalid=\"false\" value=\"General Signup FR\"><\/span><p style=\"display: none !important;\" class=\"akismet-fields-container\" data-prefix=\"_wpcf7_ak_\"><label>&#916;<textarea name=\"_wpcf7_ak_hp_textarea\" cols=\"45\" rows=\"8\" maxlength=\"100\"><\/textarea><\/label><input type=\"hidden\" id=\"ak_js_1\" name=\"_wpcf7_ak_js\" value=\"197\"\/><script>\ndocument.getElementById( \"ak_js_1\" ).setAttribute( \"value\", ( new Date() ).getTime() );\n<\/script>\n<\/p><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<\/form>\n<\/div>\n[\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>[vc_row][vc_column][vc_raw_html]JTNDZGl2JTIwY2xhc3MlM0QlMjJmYi1saWtlJTIyJTIwZGF0YS1ocmVmJTNEJTIyaHR0cHMlM0ElMkYlMkZmYWNlYm9vay5jb20lMkZjdXBlb250YXJpbyUyMiUyMGRhdGEtbGF5b3V0JTNEJTIyc3RhbmRhcmQlMjIlMjBkYXRhLWFjdGlvbiUzRCUyMmxpa2UlMjIlMjBkYXRhLXNpemUlM0QlMjJsYXJnZSUyMiUyMGRhdGEtc2hvdy1mYWNlcyUzRCUyMnRydWUlMjIlMjBkYXRhLXNoYXJlJTNEJTIyZmFsc2UlMjIlM0UlM0MlMkZkaXYlM0U=[\/vc_raw_html][vc_column_text]TORONTO (ONTARIO) \u2013\u00a0Le budget provincial d\u00e9pos\u00e9 hier par le ministre des Finances, Peter Bethlenfalvy, repr\u00e9sente une \u00ab\u00a0n\u00e9gligence crasse des devoirs\u00a0\u00bb du gouvernement conservateur Ford envers le secteur universitaire ontarien, selon David Simao, pr\u00e9sident du Comit\u00e9 de coordination des travailleurs universitaires de l\u2019Ontario (CCTUO), qui parle au nom de plus de 30\u2009000 travailleurs universitaires repr\u00e9sent\u00e9s par&hellip;<\/p>\n","protected":false},"author":5,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[211],"tags":[],"class_list":["post-40835","post","type-post","status-publish","format-standard","hentry","category-universite","category-211","description-off"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Pour le secteur universitaire en crise, le budget 2021 des conservateurs de Ford repr\u00e9sente une \u00ab n\u00e9gligence crasse de ses devoirs \u00bb, selon le pr\u00e9sident du secteur universitaire au SCFP-Ontario - SCFP-Ontario<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cupe.on.ca\/fr\/pour-le-secteur-universitaire-en-crise-le-budget-2021-des-conservateurs-de-ford-represente-une-negligence-crasse-de-ses-devoirs-selon-le-president-du-secteur-universitaire-au-scfp-onta\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pour le secteur universitaire en crise, le budget 2021 des conservateurs de Ford repr\u00e9sente une \u00ab n\u00e9gligence crasse de ses devoirs \u00bb, selon le pr\u00e9sident du secteur universitaire au SCFP-Ontario - SCFP-Ontario\" \/>\n<meta property=\"og:description\" content=\"[vc_row][vc_column][vc_raw_html]JTNDZGl2JTIwY2xhc3MlM0QlMjJmYi1saWtlJTIyJTIwZGF0YS1ocmVmJTNEJTIyaHR0cHMlM0ElMkYlMkZmYWNlYm9vay5jb20lMkZjdXBlb250YXJpbyUyMiUyMGRhdGEtbGF5b3V0JTNEJTIyc3RhbmRhcmQlMjIlMjBkYXRhLWFjdGlvbiUzRCUyMmxpa2UlMjIlMjBkYXRhLXNpemUlM0QlMjJsYXJnZSUyMiUyMGRhdGEtc2hvdy1mYWNlcyUzRCUyMnRydWUlMjIlMjBkYXRhLXNoYXJlJTNEJTIyZmFsc2UlMjIlM0UlM0MlMkZkaXYlM0U=[\/vc_raw_html][vc_column_text]TORONTO (ONTARIO) \u2013\u00a0Le budget provincial d\u00e9pos\u00e9 hier par le ministre des Finances, Peter Bethlenfalvy, repr\u00e9sente une \u00ab\u00a0n\u00e9gligence crasse des devoirs\u00a0\u00bb du gouvernement conservateur Ford envers le secteur universitaire ontarien, selon David Simao, pr\u00e9sident du Comit\u00e9 de coordination des travailleurs universitaires de l\u2019Ontario (CCTUO), qui parle au nom de plus de 30\u2009000 travailleurs universitaires repr\u00e9sent\u00e9s par&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cupe.on.ca\/fr\/pour-le-secteur-universitaire-en-crise-le-budget-2021-des-conservateurs-de-ford-represente-une-negligence-crasse-de-ses-devoirs-selon-le-president-du-secteur-universitaire-au-scfp-onta\/\" \/>\n<meta property=\"og:site_name\" content=\"SCFP-Ontario\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/CUPEOntario\" \/>\n<meta property=\"article:published_time\" content=\"2021-03-26T14:53:47+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-03-29T14:56:46+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cupe.on.ca\/wp-content\/uploads\/2021\/03\/Queens-Park-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1707\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Jessica Gale\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/cupe.on.ca\/wp-content\/uploads\/2021\/03\/Queens-Park-scaled.jpg\" \/>\n<meta name=\"twitter:creator\" content=\"@CUPEOntario\" \/>\n<meta name=\"twitter:site\" content=\"@CUPEOntario\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/cupe.on.ca\\\/fr\\\/pour-le-secteur-universitaire-en-crise-le-budget-2021-des-conservateurs-de-ford-represente-une-negligence-crasse-de-ses-devoirs-selon-le-president-du-secteur-universitaire-au-scfp-onta\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cupe.on.ca\\\/fr\\\/pour-le-secteur-universitaire-en-crise-le-budget-2021-des-conservateurs-de-ford-represente-une-negligence-crasse-de-ses-devoirs-selon-le-president-du-secteur-universitaire-au-scfp-onta\\\/\"},\"author\":{\"name\":\"Jessica Gale\",\"@id\":\"https:\\\/\\\/cupe.on.ca\\\/fr\\\/#\\\/schema\\\/person\\\/1ea3704a2eb766eca9b04bfa42217228\"},\"headline\":\"Pour le secteur universitaire en crise, le budget 2021 des conservateurs de Ford repr\u00e9sente une \u00ab n\u00e9gligence crasse de ses devoirs \u00bb, selon le pr\u00e9sident du secteur universitaire au SCFP-Ontario\",\"datePublished\":\"2021-03-26T14:53:47+00:00\",\"dateModified\":\"2021-03-29T14:56:46+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/cupe.on.ca\\\/fr\\\/pour-le-secteur-universitaire-en-crise-le-budget-2021-des-conservateurs-de-ford-represente-une-negligence-crasse-de-ses-devoirs-selon-le-president-du-secteur-universitaire-au-scfp-onta\\\/\"},\"wordCount\":793,\"articleSection\":[\"Universit\u00e9\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/cupe.on.ca\\\/fr\\\/pour-le-secteur-universitaire-en-crise-le-budget-2021-des-conservateurs-de-ford-represente-une-negligence-crasse-de-ses-devoirs-selon-le-president-du-secteur-universitaire-au-scfp-onta\\\/\",\"url\":\"https:\\\/\\\/cupe.on.ca\\\/fr\\\/pour-le-secteur-universitaire-en-crise-le-budget-2021-des-conservateurs-de-ford-represente-une-negligence-crasse-de-ses-devoirs-selon-le-president-du-secteur-universitaire-au-scfp-onta\\\/\",\"name\":\"Pour le secteur universitaire en crise, le budget 2021 des conservateurs de Ford repr\u00e9sente une \u00ab n\u00e9gligence crasse de ses devoirs \u00bb, selon le pr\u00e9sident du secteur universitaire au SCFP-Ontario - SCFP-Ontario\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cupe.on.ca\\\/fr\\\/#website\"},\"datePublished\":\"2021-03-26T14:53:47+00:00\",\"dateModified\":\"2021-03-29T14:56:46+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/cupe.on.ca\\\/fr\\\/#\\\/schema\\\/person\\\/1ea3704a2eb766eca9b04bfa42217228\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/cupe.on.ca\\\/fr\\\/pour-le-secteur-universitaire-en-crise-le-budget-2021-des-conservateurs-de-ford-represente-une-negligence-crasse-de-ses-devoirs-selon-le-president-du-secteur-universitaire-au-scfp-onta\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/cupe.on.ca\\\/fr\\\/pour-le-secteur-universitaire-en-crise-le-budget-2021-des-conservateurs-de-ford-represente-une-negligence-crasse-de-ses-devoirs-selon-le-president-du-secteur-universitaire-au-scfp-onta\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/cupe.on.ca\\\/fr\\\/pour-le-secteur-universitaire-en-crise-le-budget-2021-des-conservateurs-de-ford-represente-une-negligence-crasse-de-ses-devoirs-selon-le-president-du-secteur-universitaire-au-scfp-onta\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/cupe.on.ca\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Pour le secteur universitaire en crise, le budget 2021 des conservateurs de Ford repr\u00e9sente une \u00ab n\u00e9gligence crasse de ses devoirs \u00bb, selon le pr\u00e9sident du secteur universitaire au SCFP-Ontario\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cupe.on.ca\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/cupe.on.ca\\\/fr\\\/\",\"name\":\"SCFP-Ontario\",\"description\":\"B\u00e2tir Un Ontario Meilleur\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/cupe.on.ca\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/cupe.on.ca\\\/fr\\\/#\\\/schema\\\/person\\\/1ea3704a2eb766eca9b04bfa42217228\",\"name\":\"Jessica Gale\",\"url\":\"https:\\\/\\\/cupe.on.ca\\\/fr\\\/author\\\/jgale\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pour le secteur universitaire en crise, le budget 2021 des conservateurs de Ford repr\u00e9sente une \u00ab n\u00e9gligence crasse de ses devoirs \u00bb, selon le pr\u00e9sident du secteur universitaire au SCFP-Ontario - SCFP-Ontario","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cupe.on.ca\/fr\/pour-le-secteur-universitaire-en-crise-le-budget-2021-des-conservateurs-de-ford-represente-une-negligence-crasse-de-ses-devoirs-selon-le-president-du-secteur-universitaire-au-scfp-onta\/","og_locale":"fr_FR","og_type":"article","og_title":"Pour le secteur universitaire en crise, le budget 2021 des conservateurs de Ford repr\u00e9sente une \u00ab n\u00e9gligence crasse de ses devoirs \u00bb, selon le pr\u00e9sident du secteur universitaire au SCFP-Ontario - SCFP-Ontario","og_description":"[vc_row][vc_column][vc_raw_html]JTNDZGl2JTIwY2xhc3MlM0QlMjJmYi1saWtlJTIyJTIwZGF0YS1ocmVmJTNEJTIyaHR0cHMlM0ElMkYlMkZmYWNlYm9vay5jb20lMkZjdXBlb250YXJpbyUyMiUyMGRhdGEtbGF5b3V0JTNEJTIyc3RhbmRhcmQlMjIlMjBkYXRhLWFjdGlvbiUzRCUyMmxpa2UlMjIlMjBkYXRhLXNpemUlM0QlMjJsYXJnZSUyMiUyMGRhdGEtc2hvdy1mYWNlcyUzRCUyMnRydWUlMjIlMjBkYXRhLXNoYXJlJTNEJTIyZmFsc2UlMjIlM0UlM0MlMkZkaXYlM0U=[\/vc_raw_html][vc_column_text]TORONTO (ONTARIO) \u2013\u00a0Le budget provincial d\u00e9pos\u00e9 hier par le ministre des Finances, Peter Bethlenfalvy, repr\u00e9sente une \u00ab\u00a0n\u00e9gligence crasse des devoirs\u00a0\u00bb du gouvernement conservateur Ford envers le secteur universitaire ontarien, selon David Simao, pr\u00e9sident du Comit\u00e9 de coordination des travailleurs universitaires de l\u2019Ontario (CCTUO), qui parle au nom de plus de 30\u2009000 travailleurs universitaires repr\u00e9sent\u00e9s par&hellip;","og_url":"https:\/\/cupe.on.ca\/fr\/pour-le-secteur-universitaire-en-crise-le-budget-2021-des-conservateurs-de-ford-represente-une-negligence-crasse-de-ses-devoirs-selon-le-president-du-secteur-universitaire-au-scfp-onta\/","og_site_name":"SCFP-Ontario","article_publisher":"https:\/\/facebook.com\/CUPEOntario","article_published_time":"2021-03-26T14:53:47+00:00","article_modified_time":"2021-03-29T14:56:46+00:00","og_image":[{"width":2560,"height":1707,"url":"https:\/\/cupe.on.ca\/wp-content\/uploads\/2021\/03\/Queens-Park-scaled.jpg","type":"image\/jpeg"}],"author":"Jessica Gale","twitter_card":"summary_large_image","twitter_image":"https:\/\/cupe.on.ca\/wp-content\/uploads\/2021\/03\/Queens-Park-scaled.jpg","twitter_creator":"@CUPEOntario","twitter_site":"@CUPEOntario","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/cupe.on.ca\/fr\/pour-le-secteur-universitaire-en-crise-le-budget-2021-des-conservateurs-de-ford-represente-une-negligence-crasse-de-ses-devoirs-selon-le-president-du-secteur-universitaire-au-scfp-onta\/#article","isPartOf":{"@id":"https:\/\/cupe.on.ca\/fr\/pour-le-secteur-universitaire-en-crise-le-budget-2021-des-conservateurs-de-ford-represente-une-negligence-crasse-de-ses-devoirs-selon-le-president-du-secteur-universitaire-au-scfp-onta\/"},"author":{"name":"Jessica Gale","@id":"https:\/\/cupe.on.ca\/fr\/#\/schema\/person\/1ea3704a2eb766eca9b04bfa42217228"},"headline":"Pour le secteur universitaire en crise, le budget 2021 des conservateurs de Ford repr\u00e9sente une \u00ab n\u00e9gligence crasse de ses devoirs \u00bb, selon le pr\u00e9sident du secteur universitaire au SCFP-Ontario","datePublished":"2021-03-26T14:53:47+00:00","dateModified":"2021-03-29T14:56:46+00:00","mainEntityOfPage":{"@id":"https:\/\/cupe.on.ca\/fr\/pour-le-secteur-universitaire-en-crise-le-budget-2021-des-conservateurs-de-ford-represente-une-negligence-crasse-de-ses-devoirs-selon-le-president-du-secteur-universitaire-au-scfp-onta\/"},"wordCount":793,"articleSection":["Universit\u00e9"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/cupe.on.ca\/fr\/pour-le-secteur-universitaire-en-crise-le-budget-2021-des-conservateurs-de-ford-represente-une-negligence-crasse-de-ses-devoirs-selon-le-president-du-secteur-universitaire-au-scfp-onta\/","url":"https:\/\/cupe.on.ca\/fr\/pour-le-secteur-universitaire-en-crise-le-budget-2021-des-conservateurs-de-ford-represente-une-negligence-crasse-de-ses-devoirs-selon-le-president-du-secteur-universitaire-au-scfp-onta\/","name":"Pour le secteur universitaire en crise, le budget 2021 des conservateurs de Ford repr\u00e9sente une \u00ab n\u00e9gligence crasse de ses devoirs \u00bb, selon le pr\u00e9sident du secteur universitaire au SCFP-Ontario - SCFP-Ontario","isPartOf":{"@id":"https:\/\/cupe.on.ca\/fr\/#website"},"datePublished":"2021-03-26T14:53:47+00:00","dateModified":"2021-03-29T14:56:46+00:00","author":{"@id":"https:\/\/cupe.on.ca\/fr\/#\/schema\/person\/1ea3704a2eb766eca9b04bfa42217228"},"breadcrumb":{"@id":"https:\/\/cupe.on.ca\/fr\/pour-le-secteur-universitaire-en-crise-le-budget-2021-des-conservateurs-de-ford-represente-une-negligence-crasse-de-ses-devoirs-selon-le-president-du-secteur-universitaire-au-scfp-onta\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cupe.on.ca\/fr\/pour-le-secteur-universitaire-en-crise-le-budget-2021-des-conservateurs-de-ford-represente-une-negligence-crasse-de-ses-devoirs-selon-le-president-du-secteur-universitaire-au-scfp-onta\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/cupe.on.ca\/fr\/pour-le-secteur-universitaire-en-crise-le-budget-2021-des-conservateurs-de-ford-represente-une-negligence-crasse-de-ses-devoirs-selon-le-president-du-secteur-universitaire-au-scfp-onta\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/cupe.on.ca\/fr\/"},{"@type":"ListItem","position":2,"name":"Pour le secteur universitaire en crise, le budget 2021 des conservateurs de Ford repr\u00e9sente une \u00ab n\u00e9gligence crasse de ses devoirs \u00bb, selon le pr\u00e9sident du secteur universitaire au SCFP-Ontario"}]},{"@type":"WebSite","@id":"https:\/\/cupe.on.ca\/fr\/#website","url":"https:\/\/cupe.on.ca\/fr\/","name":"SCFP-Ontario","description":"B\u00e2tir Un Ontario Meilleur","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cupe.on.ca\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/cupe.on.ca\/fr\/#\/schema\/person\/1ea3704a2eb766eca9b04bfa42217228","name":"Jessica Gale","url":"https:\/\/cupe.on.ca\/fr\/author\/jgale\/"}]}},"_links":{"self":[{"href":"https:\/\/cupe.on.ca\/fr\/wp-json\/wp\/v2\/posts\/40835","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cupe.on.ca\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cupe.on.ca\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cupe.on.ca\/fr\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/cupe.on.ca\/fr\/wp-json\/wp\/v2\/comments?post=40835"}],"version-history":[{"count":0,"href":"https:\/\/cupe.on.ca\/fr\/wp-json\/wp\/v2\/posts\/40835\/revisions"}],"wp:attachment":[{"href":"https:\/\/cupe.on.ca\/fr\/wp-json\/wp\/v2\/media?parent=40835"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cupe.on.ca\/fr\/wp-json\/wp\/v2\/categories?post=40835"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cupe.on.ca\/fr\/wp-json\/wp\/v2\/tags?post=40835"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}